{"id":17619,"date":"2017-04-21T19:55:08","date_gmt":"2017-04-21T17:55:08","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=17619"},"modified":"2017-10-09T17:29:31","modified_gmt":"2017-10-09T15:29:31","slug":"diario-di-uno-straniero-giorno-2-arrivo-a-londra","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/","title":{"rendered":"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra"},"content":{"rendered":"<p>Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese.<br \/>\nPensieri, speranze, chilometri di strade e tanta, tanta musica.<br \/>\n<strong>Giovanni Facelli<\/strong>, cantante de <a href=\"http:\/\/www.lostraniero.eu\/\" target=\"_blank\"><span style=\"font-size: 14pt;\"><strong>Lo straniero<\/strong><\/span><\/a>, scrive in esclusiva per noi il diario di viaggio del <a href=\"http:\/\/www.piuomenopop.it\/index.php\/2017\/04\/20\/lo-straniero-da-oggi-la-band-e-in-tour-a-londra-con-quattro-appuntamenti-live\/\" target=\"_blank\">mini tour inglese<\/a> che vede impegnata in questi giorni la band piemontese sui palchi di Londra.<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>Lo Straniero mini tour UK<\/strong><\/span><\/p>\n<p><em><strong>Giorno 2 Arrivo a Londra<\/strong><\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17623\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072761_10154830141652912_71026363_n.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072761_10154830141652912_71026363_n.jpg 480w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072761_10154830141652912_71026363_n-326x245.jpg 326w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072761_10154830141652912_71026363_n-80x60.jpg 80w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072761_10154830141652912_71026363_n-300x225.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072761_10154830141652912_71026363_n-768x576.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Gioved\u00ec mattina ripartiamo alle 8 da <strong>Cambrai<\/strong>. Benzina e colazione in un&#8217;area di servizio. Un quarantenne con fuoristrada ci chiede di fare ponte perch\u00e9 il suo mezzo non parte. Ad aiutarlo un camionista munito di sandwich che non teme le scintille delle pinze. L&#8217;auto si accende e l&#8217;uomo ci lascia 10 euro per il supporto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17622\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034595_10154830141837912_899738307_n.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034595_10154830141837912_899738307_n.jpg 480w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034595_10154830141837912_899738307_n-326x245.jpg 326w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034595_10154830141837912_899738307_n-80x60.jpg 80w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034595_10154830141837912_899738307_n-300x225.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034595_10154830141837912_899738307_n-768x576.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Arrivati al porto di <strong>Calais<\/strong> riusciamo ad acquistare un biglietto a prezzo scontato e ad imbarcarci dopo un&#8217;ora. I controlli sono severi: soldati con i mitra, cani e lenti d&#8217;ingrandimento. I doganieri francesi aprono il bagagliaio e vedendo gli strumenti ci lasciano subito passare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17624\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18042901_10154830141007912_1776128056_o.jpg\" alt=\"\" width=\"500\" height=\"282\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18042901_10154830141007912_1776128056_o.jpg 568w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18042901_10154830141007912_1776128056_o-300x169.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18042901_10154830141007912_1776128056_o-768x433.jpg 768w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18042901_10154830141007912_1776128056_o-1024x577.jpg 1024w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18042901_10154830141007912_1776128056_o-243x136.jpg 243w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Alla dogana inglese, invece, vengo richiamato dal personale perch\u00e9 la mia carta d&#8217;identit\u00e0 \u00e8 leggermente usurata. L&#8217;uomo dice che per entrare nel Regno Unito i documenti devono essere integri. Ci trattengono per 15 minuti, poi finalmente saliamo sul traghetto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17625\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18090483_10154830140817912_211081212_o.jpg\" alt=\"\" width=\"500\" height=\"281\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18090483_10154830140817912_211081212_o.jpg 516w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18090483_10154830140817912_211081212_o-300x169.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18090483_10154830140817912_211081212_o-768x432.jpg 768w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18090483_10154830140817912_211081212_o-1024x576.jpg 1024w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18090483_10154830140817912_211081212_o-243x136.jpg 243w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>A bordo c&#8217;\u00e8 un pub e <strong>la gente beve birra al mattino<\/strong>, autotrasportatori e file di anziani si ingozzano di patate, porridge e pesce fritto. Nessuno fra i passeggeri parla ad alta voce.<\/p>\n<p>Sbarchiamo a <strong>Dover<\/strong> dopo un&#8217;ora e mezza. Luca e Fra scelgono <em>Ocean Rain<\/em> degli Echo and the Bunnymen come colonna sonora per questo tratto. Mi addormento. Luca guida per tutto questo tratto. In due ore siamo nell&#8217;appartamento che abbiamo affittato vicino al <strong>Victoria Park<\/strong> nell&#8217;<strong>East Finchley<\/strong>.<br \/>\nJonathan non \u00e8 il proprietario di casa, ci introduce solamente e se ne va. L&#8217;appartamento \u00e8 grande.<\/p>\n<p>Nuvole litigano sulla citt\u00e0. Arriviamo al <strong>Nambucca<\/strong>. Gi\u00e0 da fuori tutto ci convince: conosciamo Zachary, proprietario e direttore artistico. Il fonico Julian \u00e8 tarchiato, fascio di nervi che non va per il sottile. Suoneremo per ultimi: le nostre facce sono sul vetro tappezzato di locandine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17626 aligncenter\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073159_10154830152827912_1807634069_n.jpg\" alt=\"\" width=\"491\" height=\"500\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073159_10154830152827912_1807634069_n.jpg 390w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073159_10154830152827912_1807634069_n-295x300.jpg 295w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073159_10154830152827912_1807634069_n-768x782.jpg 768w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073159_10154830152827912_1807634069_n-60x60.jpg 60w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/p>\n<p>Qui si suona sei giorni su sette, il locale \u00e8 grande e il palco pu\u00f2 ricordare quello dello spazio211 di Torino. In fondo alla sala c&#8217;\u00e8 il bancone, ancora oltre sedie, tavoli e un biliardo. Dice che in 5 minuti dobbiamo scaricare ed essere sul palco, niente birre, sigarette o il tempo di rilassarsi. Luca in pochissimo tempo ha gi\u00e0 montato la sua astronave. Il suono \u00e8 subito splendido. Professionalit\u00e0, attenzione e gentilezza: sembrano le parole chiave di uno spot, ma qui \u00e8 la realt\u00e0. Proviamo due brani, il sequencer viene amplificato come vorremmo che succedesse sempre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17627\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18053190_10154830152847912_478756756_o.jpg\" alt=\"\" width=\"500\" height=\"281\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18053190_10154830152847912_478756756_o.jpg 516w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18053190_10154830152847912_478756756_o-300x169.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18053190_10154830152847912_478756756_o-768x432.jpg 768w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18053190_10154830152847912_478756756_o-1024x576.jpg 1024w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18053190_10154830152847912_478756756_o-243x136.jpg 243w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Ceniamo in un ristorante indiano. Ci servono a turno padre e figlio che fra un piatto e l&#8217;altro gioca malinconicamente con un raggio laser. \u00c8 un quartiere popolare, di strade che offrono poco, mi dicono che qui c&#8217;\u00e8 la comunit\u00e0 nigeriana pi\u00f9 numerosa della citt\u00e0. Arriviamo al<strong> Nambucca<\/strong> che il primo gruppo ha gi\u00e0 suonato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17628 aligncenter\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072595_10154830153232912_247544827_n.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072595_10154830153232912_247544827_n.jpg 480w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072595_10154830153232912_247544827_n-326x245.jpg 326w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072595_10154830153232912_247544827_n-80x60.jpg 80w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072595_10154830153232912_247544827_n-300x225.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18072595_10154830153232912_247544827_n-768x576.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Il secondo sono i <strong>Wyns<\/strong>: se la cavano alla grande. Un amico ci conduce nella green room, <strong>un sotterraneo di viottoli e stanze dove ci prepariamo per il live<\/strong>. \u00c8 un gioved\u00ec, ci sono una cinquantina di persone e l&#8217;atmosfera \u00e8 da weekend: la musica suona ad alto volume, definita. Nella pausa passano gli Stone Roses e con Fede ci esaltiamo non poco prima di salire.<\/p>\n<p>Il live parte con qualche problema di ascolto sul palco, ma il pubblico reagisce cos\u00ec bene che tiriamo dritti. Dopo tre brani si gira molto meglio e c&#8217;\u00e8 pi\u00f9 pacca: delle ragazze ballano,<strong> la met\u00e0 del pubblico \u00e8 di italiani<\/strong>. La scaletta \u00e8 incisiva perch\u00e9 suoniamo solo i singoli e i pezzi veloci. Su <strong><em>L&#8217;ultima primavera<\/em><\/strong> il pubblico tiene il tempo con le mani, poi Luca e Vale lanciano <em><strong>&#8220;Il Veliero&#8221;<\/strong><\/em> di <strong>Battisti<\/strong> e siamo gi\u00e0 alla fine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17629 aligncenter\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073622_10154830167202912_353571877_n.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073622_10154830167202912_353571877_n.jpg 480w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073622_10154830167202912_353571877_n-326x245.jpg 326w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073622_10154830167202912_353571877_n-80x60.jpg 80w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073622_10154830167202912_353571877_n-300x225.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18073622_10154830167202912_353571877_n-768x576.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Parte subito il dj-set. Da adesso \u00e8 tutto velocissimo. Ci fermano per complimentarsi e il fonico dice &#8220;cool sound&#8221;, gli regaliamo un disco. La serata sta per finire: la gente si gode quello che ormai \u00e8 un sottofondo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17630\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/londra1-1.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/londra1-1.jpg 320w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/londra1-1-80x60.jpg 80w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/londra1-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>I tavoli sono pieni di free press di musica e arte usciti negli ultimi mesi. <strong>Il locale alle undici e mezza \u00e8 ormai vuoto<\/strong>. Leggiamo, ci rilassiamo, carichiamo l&#8217;auto senza correre ormai pronti per rientrare nella nostra dimora provvisoria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17631\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034634_10154830167187912_833626248_n.jpg\" alt=\"\" width=\"375\" height=\"500\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034634_10154830167187912_833626248_n.jpg 360w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/18034634_10154830167187912_833626248_n-225x300.jpg 225w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p><strong>Leggi anche:\u00a0<a href=\"http:\/\/www.piuomenopop.it\/index.php\/2017\/04\/20\/diario-di-uno-straniero-la-partenza\/\" target=\"_blank\">Diario di uno Straniero \u2013 La partenza<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/\" title=\"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":17620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[2399,598,3],"tags":[210],"class_list":["post-17619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cantautorato","category-extra-pop","category-news","tag-lo-straniero"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redazione\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-21T17:55:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-10-09T15:29:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#blogposting\",\"name\":\"Diario di uno Straniero \\u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP\",\"headline\":\"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/londra1.jpg\",\"width\":320,\"height\":240},\"datePublished\":\"2017-04-21T19:55:08+02:00\",\"dateModified\":\"2017-10-09T17:29:31+02:00\",\"inLanguage\":\"it-IT\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#webpage\"},\"articleSection\":\"Cantautorato, Extra POP, Notizie, Lo Straniero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#listItem\",\"name\":\"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#listItem\",\"position\":3,\"name\":\"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Logo-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Redazione\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/\",\"name\":\"Diario di uno Straniero \\u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP\",\"description\":\"Una delle band pi\\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/londra1.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#mainImage\",\"width\":320,\"height\":240},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/04\\\/21\\\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\\\/#mainImage\"},\"datePublished\":\"2017-04-21T19:55:08+02:00\",\"dateModified\":\"2017-10-09T17:29:31+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP","description":"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#blogposting","name":"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP","headline":"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/londra1.jpg","width":320,"height":240},"datePublished":"2017-04-21T19:55:08+02:00","dateModified":"2017-10-09T17:29:31+02:00","inLanguage":"it-IT","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#webpage"},"articleSection":"Cantautorato, Extra POP, Notizie, Lo Straniero"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","position":2,"name":"Notizie","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#listItem","name":"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#listItem","position":3,"name":"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/","name":"Redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#authorImage","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/05\/Logo-150x150.jpg","width":96,"height":96,"caption":"Redazione"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/","name":"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP","description":"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/04\/londra1.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#mainImage","width":320,"height":240},"primaryImageOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/#mainImage"},"datePublished":"2017-04-21T19:55:08+02:00","dateModified":"2017-10-09T17:29:31+02:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP","og:description":"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra.","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/","article:published_time":"2017-04-21T17:55:08+00:00","article:modified_time":"2017-10-09T15:29:31+00:00","twitter:card":"summary","twitter:title":"Diario di uno Straniero \u2013 Giorno 2 Arrivo a Londra - Piu o Meno POP","twitter:description":"Una delle band pi\u00f9 interessanti del panorama italiano e la loro prima campagna Inglese. Pensieri, speranze, chilometri di strade e tanta, tanta musica. Giovanni Facelli, cantante de Lo straniero, scrive in esclusiva per noi il diario di viaggio del mini tour inglese che vede impegnata in questi giorni la band piemontese sui palchi di Londra."},"aioseo_meta_data":{"post_id":"17619","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 16:18:10","updated":"2026-06-22 03:49:44","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/\" title=\"Notizie\">Notizie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDiario di uno Straniero \u2013 Giorno 2 Arrivo a Londra\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Notizie","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/"},{"label":"Diario di uno Straniero &#8211; Giorno 2 Arrivo a Londra","link":"https:\/\/www.piuomenopop.it\/index.php\/2017\/04\/21\/diario-di-uno-straniero-giorno-2-arrivo-a-londra\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/17619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=17619"}],"version-history":[{"count":3,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/17619\/revisions"}],"predecessor-version":[{"id":17633,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/17619\/revisions\/17633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/17620"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=17619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=17619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=17619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}