{"id":1927,"date":"2016-06-09T18:33:37","date_gmt":"2016-06-09T16:33:37","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=1927"},"modified":"2018-01-01T19:36:31","modified_gmt":"2018-01-01T18:36:31","slug":"kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/","title":{"rendered":"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1935 aligncenter\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/06\/IMG_9824-e1465495383750.jpg\" alt=\"Foto di Francesco Farina\" width=\"524\" height=\"349\" \/><\/p>\n<p><span class=\"_5yl5\">Una notte serena e un cielo stellato, un centro storico che rappresenta la citt\u00e0 in tutte le sue contraddizioni, nobile, trascurato, all\u2019apparenza abbandonato ma pulsante di energia, una rassegna che, giunta alla sua ventesima edizione, costituisce un appuntamento imperdibile che unisce moda, cinema e musica in un cocktail artistico perfetto. Il live di <a href=\"https:\/\/www.facebook.com\/calivius\/?fref=nf\">Alessio Calivi<\/a> si svolge proprio in coda alla serata dedicata al cinema di <a href=\"http:\/\/www.modamovie.it\">Moda Movie<\/a>, dopo l\u2019ammaliante esibizione del Maestro Paolo Vivaldi, autore di innumerevoli colonne sonore per il cinema, il teatro e la televisione (da\u201dRino Gaetano\u201d di Marco Turco con Claudio Santamaria, fino alla colonna sonora del celebre, ultimo, film di Claudio Caligari \u201cNon essere cattivo\u201d), accompagnato da <a href=\"https:\/\/www.facebook.com\/mirko.onofrio.1?fref=ts\">Mirko Onofrio<\/a> (Brunori SAS, Red Basica) al sax. <\/span><\/p>\n<p><span class=\"_5yl5\">Il progetto di Alessio aka <strong>Kim Ree Heena<\/strong> si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza, sorprendendo, in maniera decisamente positiva, sia chi aveva gi\u00e0 ascoltato i suoi precedenti lavori sia chi, probabilmente la maggior parte dei presenti, non lo conosceva. Alessio si sistema alla sinistra del palco, lasciando il centro della ribalta alle ipnotiche immagini realizzate da Noil Klune, artista visuale originario anche lui di Taurianova col quale Alessio\/Kim collabora da tempo. <\/span><\/p>\n<p><span class=\"_5yl5\">Un incedere avvolgente e trascinante che coinvolge emotivamente ed ammalia esteticamente grazie all\u2019accoppiata musica\/immagini che Alessio d\u00e0 l\u2019idea di padroneggiare in maniera egregia nonostante si tratti sostanzialmente della data zero di un progetto che ancora \u00e8 in divenire. Ma anche solo questa sorta di incipit \u00e8 assolutamente intrigante: Alessio ha creato un tessuto sonoro fitto e ben equilibrato, mettendo in pratica oltre alle sue indubbie capacit\u00e0 artistiche anche l\u2019esperienza fatta nell\u2019ambito del \u201csound engeneering\u201d. Ci\u00f2 che sorprende di pi\u00f9 in questo live \u00e8 la perfetta sincronia tra immagini e suoni, quasi come se fossero realizzati dal vivo contemporaneamente e dalla stessa persona, per quanto viaggiano in accordo reciproco. A spiccare, tra i 3 pezzi dell\u2019esibizione, \u00e8 <em>&#8220;Kim&#8221;<\/em> l\u2019unico brano cantato, una scelta decisamente coraggiosa per un pezzo che, anche solo come strumentale, sarebbe stato un piccolo gioiello ma che il testo e la voce di Alessio impreziosiscono ancora di pi\u00f9. <\/span><\/p>\n<p><span class=\"_5yl5\">Una performance che se da un lato rispecchia a pieno quello che \u00e8 stato il leit motiv di questa edizione di <strong>ModaMovie<\/strong>, piantando i piedi \u201cnel presente\u201d in maniera salda e decisa, dall\u2019altro con i suoi suoni moderni ma tutt\u2019altro che asettici volge lo sguardo a un futuro vivo e reale. Una performance che apre, senza alcun dubbio, orizzonti nuovi alla carriera di Alessio, che decide di osare e di scommettere su se stesso e sulle sue abilit\u00e0. Gli applausi del pubblico in sala al termine dell\u2019esibizione e lo sguardo soddisfatto dello stesso musicista calabrese non mentono: la scommessa Kim Ree Heena ha proprio tutto per diventare una scommessa vincente.<\/span><\/p>\n<p>Foto di Francesco Farina<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Una notte serena e un cielo stellato, un centro storico che rappresenta la citt\u00e0 in tutte le sue contraddizioni, nobile, trascurato, all\u2019apparenza abbandonato ma pulsante <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/\" title=\"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":10,"featured_media":1373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[236,8,5],"tags":[296,414,253],"class_list":["post-1927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elettronica","category-uscite","category-report","tag-alessio-calivi","tag-kim-ree-heena","tag-moda-movie"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Renata Rossi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kim Ree Heena, &quot;nel presente&quot; con uno sguardo al futuro | Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-09T16:33:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-01-01T18:36:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kim Ree Heena, &quot;nel presente&quot; con uno sguardo al futuro | Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#blogposting\",\"name\":\"Kim Ree Heena, \\\"nel presente\\\" con uno sguardo al futuro | Piu o Meno POP\",\"headline\":\"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/renatarossi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/13232906_1139931379362915_3179905987413586555_n.jpg\",\"width\":340,\"height\":480},\"datePublished\":\"2016-06-09T18:33:37+02:00\",\"dateModified\":\"2018-01-01T19:36:31+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#webpage\"},\"articleSection\":\"Elettronica, Nuove uscite, Report Concerti, Alessio Calivi, Kim Ree Heena, MODA MOVIE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/report\\\/#listItem\",\"name\":\"Report Concerti\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/report\\\/#listItem\",\"position\":2,\"name\":\"Report Concerti\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/report\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#listItem\",\"name\":\"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#listItem\",\"position\":3,\"name\":\"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/report\\\/#listItem\",\"name\":\"Report Concerti\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/renatarossi\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/renatarossi\\\/\",\"name\":\"Renata Rossi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/rex-e1473366836657-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Renata Rossi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/\",\"name\":\"Kim Ree Heena, \\\"nel presente\\\" con uno sguardo al futuro | Piu o Meno POP\",\"description\":\"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/renatarossi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/renatarossi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/13232906_1139931379362915_3179905987413586555_n.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#mainImage\",\"width\":340,\"height\":480},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/06\\\/09\\\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\\\/#mainImage\"},\"datePublished\":\"2016-06-09T18:33:37+02:00\",\"dateModified\":\"2018-01-01T19:36:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kim Ree Heena, \"nel presente\" con uno sguardo al futuro | Piu o Meno POP","description":"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#blogposting","name":"Kim Ree Heena, \"nel presente\" con uno sguardo al futuro | Piu o Meno POP","headline":"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/renatarossi\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/05\/13232906_1139931379362915_3179905987413586555_n.jpg","width":340,"height":480},"datePublished":"2016-06-09T18:33:37+02:00","dateModified":"2018-01-01T19:36:31+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#webpage"},"articleSection":"Elettronica, Nuove uscite, Report Concerti, Alessio Calivi, Kim Ree Heena, MODA MOVIE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/report\/#listItem","name":"Report Concerti"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/report\/#listItem","position":2,"name":"Report Concerti","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/report\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#listItem","name":"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#listItem","position":3,"name":"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/report\/#listItem","name":"Report Concerti"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/renatarossi\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/renatarossi\/","name":"Renata Rossi","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#authorImage","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/09\/rex-e1473366836657-150x150.jpg","width":96,"height":96,"caption":"Renata Rossi"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/","name":"Kim Ree Heena, \"nel presente\" con uno sguardo al futuro | Piu o Meno POP","description":"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/renatarossi\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/renatarossi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/05\/13232906_1139931379362915_3179905987413586555_n.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#mainImage","width":340,"height":480},"primaryImageOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/#mainImage"},"datePublished":"2016-06-09T18:33:37+02:00","dateModified":"2018-01-01T19:36:31+01:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"Kim Ree Heena, &quot;nel presente&quot; con uno sguardo al futuro | Piu o Meno POP","og:description":"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/","article:published_time":"2016-06-09T16:33:37+00:00","article:modified_time":"2018-01-01T18:36:31+00:00","twitter:card":"summary","twitter:title":"Kim Ree Heena, &quot;nel presente&quot; con uno sguardo al futuro | Piu o Meno POP","twitter:description":"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,"},"aioseo_meta_data":{"post_id":"1927","title":"Kim Ree Heena, &quot;nel presente&quot; con uno sguardo al futuro | #site_title","description":"Il progetto di Alessio aka Kim Ree Heena si discosta in maniera netta da tutto quello che il musicista di Taurianova aveva realizzato in precedenza,","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 12:09:10","updated":"2026-06-21 23:51:46","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/report\/\" title=\"Report Concerti\">Report Concerti<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKim Ree Heena, \u201cnel presente\u201d con uno sguardo al futuro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Report Concerti","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/report\/"},{"label":"Kim Ree Heena, &#8220;nel presente&#8221; con uno sguardo al futuro","link":"https:\/\/www.piuomenopop.it\/index.php\/2016\/06\/09\/kim-ree-heena-nel-presente-con-uno-sguardo-al-futuro\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/1927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=1927"}],"version-history":[{"count":8,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/1927\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/1927\/revisions\/1948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/1373"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=1927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=1927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=1927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}