{"id":26436,"date":"2017-11-05T10:53:03","date_gmt":"2017-11-05T09:53:03","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=26436"},"modified":"2017-11-05T10:53:03","modified_gmt":"2017-11-05T09:53:03","slug":"belize-e-uscito-replica-il-nuovo-ep","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/05\/belize-e-uscito-replica-il-nuovo-ep\/","title":{"rendered":"BELIZE: E&#8217; uscito &#8220;Replica&#8221;, il nuovo EP"},"content":{"rendered":"<figure id=\"attachment_26437\" aria-describedby=\"caption-attachment-26437\" style=\"width: 250px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26437\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/BELIZE_REPLICA_cover.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/BELIZE_REPLICA_cover.jpg 250w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/BELIZE_REPLICA_cover-150x150.jpg 150w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/BELIZE_REPLICA_cover-60x60.jpg 60w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><figcaption id=\"caption-attachment-26437\" class=\"wp-caption-text\">Artwork: Aloha Project<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>&#8220;Replica&#8221;<\/strong> \u00e8 il nuovo EP dei <strong><a href=\"https:\/\/www.facebook.com\/noisiamoibelize\" target=\"_blank\" rel=\"noopener\">BELIZE<\/a>,<\/strong> disponibile dal <strong>3 novembre<\/strong> su iTunes, Spotify e tutte le principali piattaforme streaming per <strong>Ghost Records<\/strong> distribuito da <strong>Believe Digital<\/strong>.<\/p>\n<p style=\"text-align: justify;\">I <strong><a href=\"https:\/\/www.facebook.com\/noisiamoibelize\" target=\"_blank\" rel=\"noopener\">BELIZE<\/a>,<\/strong> sono una band di Varese attiva dal 2014. Il loro sound ricercato ed essenziale esplora le varie sfaccettature della musica urban pi\u00f9 attuale, scomponendo e ricomponendo mondi sonori influenzati dall&#8217;elettronica, dal rap e dal trip hop con suoni e stili contemporanei di derivazione pop. Dopo il loro album d&#8217;esordio<strong> \u201cSpazioperso\u201d<\/strong> nel 2016 i <strong><a href=\"https:\/\/www.facebook.com\/noisiamoibelize\" target=\"_blank\" rel=\"noopener\">BELIZE<\/a>,<\/strong>hanno conquistato la stampa specializzata e intrapreso un fortunato tour nei club e nei festival, candidandosi come uno dei nomi pi\u00f9 originali e interessanti del panorama indipendente italiano.<\/p>\n<p style=\"text-align: justify;\">Il nuovo EP <strong>&#8220;Replica&#8221;<\/strong> \u00e8 un susseguirsi di atmosfere rarefatte e soffuse tra elettronica downtempo e un pop elegante e nuovo dalla fortissima connotazione personale. I <strong><a href=\"https:\/\/www.facebook.com\/noisiamoibelize\" target=\"_blank\" rel=\"noopener\">BELIZE<\/a>,<\/strong> condensano nei loro brani momenti di rottura, scelte e cambiamenti, in un&#8217;istantanea di chi si sta affacciando all&#8217;et\u00e0 adulta accettando con estrema onest\u00e0 la convivenza con i lati pi\u00f9 complessi del proprio io.<\/p>\n<p style=\"text-align: justify;\">Tutte le strumentali sono state composte ed arrangiate dai <strong><a href=\"https:\/\/www.facebook.com\/noisiamoibelize\" target=\"_blank\" rel=\"noopener\">BELIZE<\/a>,<\/strong> in collaborazione con Giacomo Carlone, che ha curato la produzione e i mix al <strong>Supermoon Studio di Milano<\/strong>. Il master \u00e8 stato affidato a Andrea \u201cBernie\u201d De Bernardi all&#8217; <strong>Eleven Mastering di Busto Arsizio<\/strong> (Va). Progetto grafico a cura di Giacomo Fumagalli (<strong>Aloha Project<\/strong>).<\/p>\n<p style=\"text-align: center;\">I <strong><a href=\"https:\/\/www.facebook.com\/noisiamoibelize\" target=\"_blank\" rel=\"noopener\">BELIZE<\/a>,<\/strong> presenteranno il loro EP con due release party ufficiali:<\/p>\n<p style=\"text-align: center;\"><strong>11.11 &#8211; Cantine Coopuf &#8211; VARESE <\/strong><br \/>\n<strong>24.11 &#8211; Circolo Magnolia &#8211; MILANO<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Leggi anche: <a href=\"http:\/\/www.piuomenopop.it\/index.php\/2017\/10\/27\/belize-fuori-il-nuovo-video-superman\/\" target=\"_blank\" rel=\"noopener\">BELIZE- fuori il nuovo video \u201cSuperman\u201d<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>&#8220;Replica&#8221; \u00e8 il nuovo EP dei BELIZE, disponibile dal 3 novembre su iTunes, Spotify e tutte le principali piattaforme streaming per Ghost Records distribuito da <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/05\/belize-e-uscito-replica-il-nuovo-ep\/\" title=\"BELIZE: E&#8217; uscito &#8220;Replica&#8221;, il nuovo EP\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":26437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,8],"tags":[449,827,146,3375,1190,4414,345],"class_list":["post-26436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uscite","tag-believe-digital","tag-belize","tag-bpm-concerti","tag-ghost-records","tag-rc-waves","tag-replica","tag-smc-italia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/26436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=26436"}],"version-history":[{"count":1,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/26436\/revisions"}],"predecessor-version":[{"id":26438,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/26436\/revisions\/26438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/26437"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=26436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=26436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=26436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}