{"id":26541,"date":"2017-11-08T13:37:27","date_gmt":"2017-11-08T12:37:27","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=26541"},"modified":"2018-01-01T14:59:01","modified_gmt":"2018-01-01T13:59:01","slug":"una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/","title":{"rendered":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26556 size-full\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/23331080_847786372054437_413680554751737802_o.jpg\" alt=\"\" width=\"700\" height=\"271\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/23331080_847786372054437_413680554751737802_o.jpg 700w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/23331080_847786372054437_413680554751737802_o-300x116.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m.<\/p>\n<p>La <strong>M di Musica<\/strong> va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento, di riflessione, di aggregazione, ecc &#8230;<\/p>\n<p>Mentre la <strong>m di mafie<\/strong> va necessariamente minuscola perch\u00e9 non ha valore, rappresenta un disvalore da sradicare laddove e allorquando lo si incontra.<\/p>\n<p>Ed ecco che un\u2019associazione,\u00a0\u00a0<strong><a href=\"https:\/\/www.facebook.com\/musicacontrolemafieofficial\/?ref=br_rs\" target=\"_blank\" rel=\"noopener\">Musica contro le mafie<\/a><\/strong>, sceglie di darsi un nome contrapponendo la M con la m.<\/p>\n<p>L\u2019associazione, sotto l\u2019egida di <a href=\"https:\/\/www.facebook.com\/libera.associazioni.nomi.e.numeri.contro.le.mafie\/\" target=\"_blank\" rel=\"noopener\"><strong>Libera Associazioni<\/strong> <strong>nomi e numeri contro le mafie,<\/strong><\/a> ed in collaborazione con un numero di realt\u00e0 anno dopo anno crescenti, d\u00e0 vita al <strong>Premio Musica contro le mafie<\/strong> che, nel 2017, \u00e8 ormai giunto alla sua ottava edizione.<\/p>\n<p>Il premio \u00e8 rivolto a cantanti, cantautori, gruppi, rapper, ecc &#8230; che hanno voglia di interpretare con le loro composizioni originali i temi dell\u2019antimafia.<\/p>\n<p>Una volta terminata la fase delle iscrizioni, il premio ha tre fasi principali:<strong> il voto su Facebook, il voto della giuria responsabile, ed il voto delle scuole.<\/strong><\/p>\n<p>Ogni giuria porter\u00e0 alla scrematura dei concorrenti fino a farli arrivare al numero di 10, infatti saranno 10 le esibizioni che tra il 15 e il 16 dicembre sul palco del Teatro Morelli di <strong>Cosenza<\/strong> si contenderanno la cifra di 15.000 euro (primo classificato), per la realizzazione di un tour, e una borsa produzione di 1000 euro (secondo classificato). I premi saranno consegnati poi durante le giornate del <strong>Festival della canzone italiana di Sanremo<\/strong> e i vincitori si esibiranno a <strong>Casa Sanremo<\/strong>.<\/p>\n<p>Il voto su Facebook al link \u00e8 partito il 7 novembre e durer\u00e0 fino al 27 novembre, per chi vuole partecipare e promuovere il brano\/artista preferito, <a href=\"https:\/\/premium.easypromosapp.com\/promotions\/813742\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"_5yl5\">qui il link per votare.<\/span><\/strong><\/a><\/p>\n<p>La giuria responsabile \u00e8 formata da 21 persone e diverse figure tra i musicisti, in mezzo ad altri troviamo,<strong> Maurizio Capone<\/strong> percussionista e titolare del progetto B<em>ungtBangt,<\/em> <strong>Kiave <\/strong>(rapper)<strong>, Rossano Lo Mele<\/strong> dei <em>Perturbazione e<\/em> <strong>Zibba<\/strong> (cantautore).<\/p>\n<p>Sempre a Cosenza nell\u2019attesa della serata finale ci sar\u00e0 \u201c<em>5 giorni di Musica contro le mafie<\/em>\u201d un ciclo di incontri, dibattiti, showcase e dj set che incomincer\u00e0 mercoled\u00ec 13 dicembre, dal 14 dicembre al loro interno per dieci ragazz*, che nel frattempo si saranno iscritt* ci sar\u00e0 un workshop dal titolo \u201c<em>L\u2019arte di far cantare la monnezza<\/em>\u201d con Maurizio Capone BungtBangt.<\/p>\n<p>Nella serata finale che sar\u00e0 sabato 16 dicembre inoltre sar\u00e0 dato un premio per il suo pezzo \u201c<em>Canzone contro la paura<\/em>\u201d a<strong> Dario Brunori<\/strong> titolare della <strong>Brunori Sas.<\/strong><\/p>\n<p>Ma il premio pi\u00f9 ambito \u00e8 e sar\u00e0 sempre quello ricevuto dai tanti ragazzi provenienti da tutta Italia: l\u2019opportunit\u00e0, attraverso la Musica, di crescere e formare o trasformare la coscienza, di renderla capace di lottare contro le mafie e di promuovere la cultura della legalit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>&nbsp; Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/\" title=\"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":26556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[43,292,4438,1972,4437,4439,4436,4440,1797,1229],"class_list":["post-26541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cosenza","tag-kiave","tag-libera-associazioni-nomi-e-numeri-contro-le-mafie","tag-maurizio-capone","tag-musica-contro-le-mafie","tag-premio-musica-contro-le-mafie","tag-rossano-lo-mele","tag-sanremo","tag-teatro-morelli","tag-zibba"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redazione\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-11-08T12:37:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-01-01T13:59:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#blogposting\",\"name\":\"Una questione di shift: Musica contro le mafie \\u00e8 giunta all\\u2019ottava edizione - Piu o Meno POP\",\"headline\":\"Una questione di shift: Musica contro le mafie \\u00e8 giunta all\\u2019ottava edizione\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/23331080_847786372054437_413680554751737802_o.jpg\",\"width\":700,\"height\":271},\"datePublished\":\"2017-11-08T13:37:27+01:00\",\"dateModified\":\"2018-01-01T14:59:01+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#webpage\"},\"articleSection\":\"Notizie, Cosenza, kiave, Libera Associazioni nomi e numeri contro le mafie, Maurizio Capone, Musica contro le mafie, Premio Musica contro le mafie, Rossano Lo Mele, Sanremo, Teatro Morelli, Zibba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#listItem\",\"name\":\"Una questione di shift: Musica contro le mafie \\u00e8 giunta all\\u2019ottava edizione\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#listItem\",\"position\":3,\"name\":\"Una questione di shift: Musica contro le mafie \\u00e8 giunta all\\u2019ottava edizione\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Logo-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Redazione\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/\",\"name\":\"Una questione di shift: Musica contro le mafie \\u00e8 giunta all\\u2019ottava edizione - Piu o Meno POP\",\"description\":\"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \\u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\\u00e9 la Musica ha un alto valore, pu\\u00f2 essere di accompagnamento,\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/23331080_847786372054437_413680554751737802_o.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#mainImage\",\"width\":700,\"height\":271},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2017\\\/11\\\/08\\\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\\\/#mainImage\"},\"datePublished\":\"2017-11-08T13:37:27+01:00\",\"dateModified\":\"2018-01-01T14:59:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP","description":"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#blogposting","name":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP","headline":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/23331080_847786372054437_413680554751737802_o.jpg","width":700,"height":271},"datePublished":"2017-11-08T13:37:27+01:00","dateModified":"2018-01-01T14:59:01+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#webpage"},"articleSection":"Notizie, Cosenza, kiave, Libera Associazioni nomi e numeri contro le mafie, Maurizio Capone, Musica contro le mafie, Premio Musica contro le mafie, Rossano Lo Mele, Sanremo, Teatro Morelli, Zibba"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","position":2,"name":"Notizie","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#listItem","name":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#listItem","position":3,"name":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/","name":"Redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#authorImage","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/05\/Logo-150x150.jpg","width":96,"height":96,"caption":"Redazione"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/","name":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP","description":"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2017\/11\/23331080_847786372054437_413680554751737802_o.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#mainImage","width":700,"height":271},"primaryImageOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/#mainImage"},"datePublished":"2017-11-08T13:37:27+01:00","dateModified":"2018-01-01T14:59:01+01:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP","og:description":"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/","article:published_time":"2017-11-08T12:37:27+00:00","article:modified_time":"2018-01-01T13:59:01+00:00","twitter:card":"summary","twitter:title":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione - Piu o Meno POP","twitter:description":"Per provare a dare il giusto valore alle parole, ce ne sono alcune che vanno riportate con l\u2019iniziale maiuscola e altre che richiedono il minuscolo, ecco che ad esempio una M \u00e8 diversa da una m. La M di Musica va sempre maiuscola, perch\u00e9 la Musica ha un alto valore, pu\u00f2 essere di accompagnamento,"},"aioseo_meta_data":{"post_id":"26541","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 15:28:37","updated":"2026-06-22 06:02:43","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/\" title=\"Notizie\">Notizie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUna questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Notizie","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/"},{"label":"Una questione di shift: Musica contro le mafie \u00e8 giunta all\u2019ottava edizione","link":"https:\/\/www.piuomenopop.it\/index.php\/2017\/11\/08\/una-questione-di-shift-musica-contro-le-mafie-e-giunta-allottava-edizione\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/26541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=26541"}],"version-history":[{"count":8,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/26541\/revisions"}],"predecessor-version":[{"id":26600,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/26541\/revisions\/26600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/26556"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=26541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=26541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=26541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}