{"id":29558,"date":"2018-01-31T13:01:10","date_gmt":"2018-01-31T12:01:10","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=29558"},"modified":"2018-01-31T13:01:10","modified_gmt":"2018-01-31T12:01:10","slug":"vanarin-la-band-bergamasca-esordisce-su-woodworm-label-con-overnight-dieci-tracce-tra-melodie-pop-ritmiche-funk-e-contaminazioni-trap","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2018\/01\/31\/vanarin-la-band-bergamasca-esordisce-su-woodworm-label-con-overnight-dieci-tracce-tra-melodie-pop-ritmiche-funk-e-contaminazioni-trap\/","title":{"rendered":"Vanarin: La band bergamasca esordisce su Woodworm Label con &#8220;Overnight&#8221;, dieci tracce tra melodie pop, ritmiche funk e contaminazioni trap"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29559 size-full\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/01\/vanarin_overnight_covercd.jpg\" alt=\"\" width=\"336\" height=\"336\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/01\/vanarin_overnight_covercd.jpg 336w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/01\/vanarin_overnight_covercd-150x150.jpg 150w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/01\/vanarin_overnight_covercd-300x300.jpg 300w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/01\/vanarin_overnight_covercd-60x60.jpg 60w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Uscir\u00e0 su <a href=\"https:\/\/www.facebook.com\/woodwormlabel\/\" target=\"_blank\" rel=\"noopener\">Woodworm Label<\/a> il 23 marzo <strong>\u201cOvernight\u201d<\/strong>, il primo album dei<a href=\"https:\/\/www.facebook.com\/vanarinmusic\/\" target=\"_blank\" rel=\"noopener\"><strong> Vanarin<\/strong><\/a>. Dieci brani, tra melodie di impronta pop e arrangiamenti ricercati. Cinque personalit\u00e0 che si intrecciano in un mix di influenze e contaminazioni, tra atmosfere beat, funk e black music degli anni \u201870, fino ad arrivare alla trap e all\u2019hip hop. Il tutto si amalgama alla perfezione, confluendo in un&#8217;unica direzione di stampo prettamente pop.<\/p>\n<p style=\"text-align: justify;\">Il disco \u00e8 frutto anche della preziosa collaborazione con <strong>Roberta Sammarelli<\/strong> (<a href=\"https:\/\/www.facebook.com\/verdenaofficial\/\" target=\"_blank\" rel=\"noopener\">Verdena<\/a>) nel ruolo di manager.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec come nell&#8217;omonimo EP d&#8217;esordio che lo ha anticipato, anche in <strong>\u201cOvernight\u201d<\/strong> non mancano gli arrangiamenti corali e i momenti di pura psichedelia, affidati agli strumenti. L\u2019album \u00e8 frutto di un lavoro durato poco meno di un anno e i brani, registrati per la maggior parte in presa diretta, sono stai prodotti quasi esclusivamente di notte, nello studio della band. I testi raccontano diversi stati d\u2019animo: un viaggio altalenante tra euforia e spensieratezza, fino all\u2019inquietudine, l\u2019apatia e la rabbia. I testi vengono affidati a chi canta la canzone, cos\u00ec come la stesura melodica e armonica di base.<\/p>\n<p style=\"text-align: justify;\">\n<a href=\"https:\/\/www.facebook.com\/vanarinmusic\/\" target=\"_blank\" rel=\"noopener\"><strong>Vanarin<\/strong><\/a> \u00e8 un progetto nato a Bergamo nel 2015, dall\u2019incontro fra il cantautore inglese David Paysden (voce, chitarra, tastiere), Marco Sciacqua (chitarra, basso, percussioni, seconde voci), Giuseppe Chiara (voce, chitarra, tastiere), Massimo Mantovani (voce, basso, chitarra) e Marco Brena (batteria, percussioni). Caratterizzato dalla continua contaminazione tra generi, passando da beat e psichedelia fino all\u2019elettronica, la trap e l\u2019hip hop, il sound della band miscela tutti questi elementi con particolare cura delle melodie, in un blend omogeneo, dall&#8217;attitudine spiccatamente pop.<\/p>\n<p style=\"text-align: justify;\">La formazione ha all\u2019attivo un EP omonimo autoprodotto di 5 brani, pubblicato il 6 gennaio 2017, a cui \u00e8 seguito un tour di circa 50 concerti in tutta Italia, tra cui le aperture a <strong>Thurston Moore, Fast Animals and Slow Kids (<a href=\"http:\/\/www.piuomenopop.it\/index.php\/2017\/08\/08\/filagosto-festival-2017-day-6-fast-animals-and-slow-kids\/\" target=\"_blank\" rel=\"noopener\">gallery qui<\/a>) , Pan delDiavolo e C+C Maxigross<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>&nbsp; Uscir\u00e0 su Woodworm Label il 23 marzo \u201cOvernight\u201d, il primo album dei Vanarin. Dieci brani, tra melodie di impronta pop e arrangiamenti ricercati. Cinque <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2018\/01\/31\/vanarin-la-band-bergamasca-esordisce-su-woodworm-label-con-overnight-dieci-tracce-tra-melodie-pop-ritmiche-funk-e-contaminazioni-trap\/\" title=\"Vanarin: La band bergamasca esordisce su Woodworm Label con &#8220;Overnight&#8221;, dieci tracce tra melodie pop, ritmiche funk e contaminazioni trap\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":29559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,8],"tags":[3828,3915,670,33],"class_list":["post-29558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uscite","tag-promorama","tag-vanarin","tag-verdena","tag-woodworm-label"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/29558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=29558"}],"version-history":[{"count":1,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/29558\/revisions"}],"predecessor-version":[{"id":29560,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/29558\/revisions\/29560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/29559"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=29558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=29558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=29558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}