{"id":30393,"date":"2018-03-06T12:00:04","date_gmt":"2018-03-06T11:00:04","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=30393"},"modified":"2018-03-03T18:41:54","modified_gmt":"2018-03-03T17:41:54","slug":"gogol-bordello-in-italia-per-un-bollente-tour-estivo","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/","title":{"rendered":"GOGOL BORDELLO: in Italia per un bollente tour estivo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Tornano in Italia i <a href=\"https:\/\/www.facebook.com\/gogolbordello\/\" target=\"_blank\" rel=\"noopener\">Gogol Bordello<\/a>!<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30394 size-full\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018.jpg\" alt=\"\" width=\"550\" height=\"413\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018.jpg 550w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018-326x245.jpg 326w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018-80x60.jpg 80w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018-300x225.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo aver infiammato i palchi di mezza penisola lo scorso anno, la band di<strong> Eugene H\u00fctz<\/strong> torna a grande richiesta nel nostro paese; gli appuntamenti estivi con i <strong><a href=\"https:\/\/www.facebook.com\/gogolbordello\/\" target=\"_blank\" rel=\"noopener\">Gogol Bordello<\/a><\/strong>sono quasi una tradizione e la loro inesauribile energia far\u00e0 tappa il prossimo luglio ai seguenti festival: <strong>il 18 luglio a Villa Arconati Music Festival, Bollate (MI), il 20 luglio alla rassegna Sullasabbia a Bellaria Igea Marina (RN), il 21 luglio al Mojotic Festival di Sestri Levante (GE) e il 22 luglio al Festival di Majano a Majano (UD).<\/strong><\/p>\n<p style=\"text-align: justify;\">I <strong><a href=\"https:\/\/www.facebook.com\/gogolbordello\/\" target=\"_blank\" rel=\"noopener\">Gogol Bordello<\/a><\/strong>, la band gipsy punk pi\u00f9 amata al mondo, capitanata dall\u2019eccentrico e talentuoso Eugene H\u00fctz, sono una vera e propria garanzia di divertimento. Una carovana di buonumore fatta di violini, tamburi e chitarre distorte, un mix unico e inconfondibile diventato il loro segno distintivo. Come dei veri e propri gipsy, non si stancano mai di girare portando il loro sound sui palchi di tutto il mondo; i loro show sono travolgenti, energici, irriverenti, Eugene e la sua ciurma sanno coinvolgere il pubblico divertendosi e divertendo chi vi assiste come pochi altri sanno fare. I meriti della band non si fermano alle sole e incredibili live performance ma hanno alle spalle, dagli inizi ad oggi, sette album in studio, tra cui i successi <strong>\u2018Super Taranta!\u2019, \u2018Gipsy Punks: Underdog World Strike\u2019<\/strong> e il pi\u00f9 recente <strong>\u2018Seekers and Finders\u2019<\/strong>, pubblicato lo scorso 25 agosto tramite Cooking Vinyl \/ Edel.<\/p>\n<p style=\"text-align: justify;\">Seekers And Finders \u00e8 il primo disco prodotto dallo stesso Eugene, che afferma:<strong><em> \u201cPer noi Seekers and Finders \u00e8 un disco magico e spensierato\u201d<\/em>.<\/strong> Si pu\u00f2 dire che il disco racchiuda la quintessenza della band, come affermato da loro stessi \u201cthe Good, the Bad and the Snugly\u201d. Scritto durante un lungo periodo di permanenza in ben tre diversi continenti, Seekers And Finders ritrova in ottima forma l\u2019essenza multiculturale dei suoi 9 componenti; violino, fisarmonica, tromba e marimba si uniscono in armonia alla classica formazione rock con chitarre, batteria e basso. <strong><em>\u201cLe canzoni stavano gi\u00e0 iniziando a emergere nel periodo in cui mi dividevo tra America Latina ed Est Europa ma alla fine \u00e8 stato non appena sono tornato a New York che tutto \u00e8 diventato pi\u00f9 chiaro e a fuoco\u2026l\u00ec \u00e8 sempre stato cos\u00ec per me\u201d<\/em><\/strong> afferma Eugene.<\/p>\n<p style=\"text-align: justify;\">Il circo gipsy punk sta per tornare!<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>GOGOL BORDELLO &#8211; 18.07.2018 @ Villa Arconati Music Festival | Bollate (MI)<\/strong><br \/>\nIngresso 25,00 \u20ac + d.d.p.<br \/>\nBiglietti disponibili a partire da venerd\u00ec 2 marzo alle ore 10.00 sui circuiti di prevendita Mailticket, Ticketone e Vivaticket.<\/p>\n<p style=\"text-align: justify;\"><strong>GOGOL BORDELLO &#8211; 20.07.2018 @ Sullasabbia | Bellaria Igea Marina (RN)<\/strong><br \/>\nIngresso 23,00 \u20ac + d.d.p.<br \/>\nBiglietti disponibili a partire da venerd\u00ec 2 marzo alle ore 10.00 sui circuiti di prevendita Mailticket, Ticketone e Ciaoticket.<\/p>\n<p style=\"text-align: justify;\"><strong>GOGOL BORDELLO 21.07.2018 @ Mojotic Festival | Sestri Levante (GE)<\/strong><br \/>\nIngresso 25,00 \u20ac + d.d.p.<br \/>\nBiglietti disponibili a partire da venerd\u00ec 2 marzo alle ore 10.00 su www.mojotic.it e sui circuiti di prevendita Ticketone, Vivaticket e DIY.<\/p>\n<p style=\"text-align: justify;\"><strong>GOGOL BORDELLO 22.07.2018 @ Festival di Majano | Majano (UD)<\/strong><br \/>\nIngresso 25,00 \u20ac + d.d.p.<br \/>\nBiglietti disponibili a partire da venerd\u00ec 2 marzo alle ore 10.00 sul circuito Ticketone.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Tornano in Italia i Gogol Bordello! Dopo aver infiammato i palchi di mezza penisola lo scorso anno, la band di Eugene H\u00fctz torna a grande <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/\" title=\"GOGOL BORDELLO: in Italia per un bollente tour estivo\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":30394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[5184,1278,3,985],"tags":[5502,2846,409,5505,5504,5503],"class_list":["post-30393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calendario-concerti","category-gipsy","category-news","category-tour","tag-festival-di-majano","tag-gogol-bordello","tag-hub-music-factory","tag-mojotic-festival","tag-sullasabbia","tag-villa-arconati-music-festival"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"GOGOL BORDELLO: in Italia per un bollente tour estivo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redazione\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"GOGOL BORDELLO: in Italia per un bollente tour estivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-06T11:00:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-03T17:41:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"GOGOL BORDELLO: in Italia per un bollente tour estivo\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#blogposting\",\"name\":\"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP\",\"headline\":\"GOGOL BORDELLO: in Italia per un bollente tour estivo\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/GOGOL-BORDELLO_2018.jpg\",\"width\":550,\"height\":413},\"datePublished\":\"2018-03-06T12:00:04+01:00\",\"dateModified\":\"2018-03-03T18:41:54+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#webpage\"},\"articleSection\":\"calendario concerti, Gipsy, Notizie, Tour, Festival di Majano, Gogol Bordello, HUB MUSIC FACTORY, Mojotic Festival, Sullasabbia, Villa Arconati Music Festival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#listItem\",\"name\":\"GOGOL BORDELLO: in Italia per un bollente tour estivo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#listItem\",\"position\":3,\"name\":\"GOGOL BORDELLO: in Italia per un bollente tour estivo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Logo-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Redazione\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/\",\"name\":\"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP\",\"description\":\"GOGOL BORDELLO: in Italia per un bollente tour estivo\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/GOGOL-BORDELLO_2018.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#mainImage\",\"width\":550,\"height\":413},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2018\\\/03\\\/06\\\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\\\/#mainImage\"},\"datePublished\":\"2018-03-06T12:00:04+01:00\",\"dateModified\":\"2018-03-03T18:41:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP","description":"GOGOL BORDELLO: in Italia per un bollente tour estivo","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#blogposting","name":"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP","headline":"GOGOL BORDELLO: in Italia per un bollente tour estivo","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018.jpg","width":550,"height":413},"datePublished":"2018-03-06T12:00:04+01:00","dateModified":"2018-03-03T18:41:54+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#webpage"},"articleSection":"calendario concerti, Gipsy, Notizie, Tour, Festival di Majano, Gogol Bordello, HUB MUSIC FACTORY, Mojotic Festival, Sullasabbia, Villa Arconati Music Festival"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","position":2,"name":"Notizie","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#listItem","name":"GOGOL BORDELLO: in Italia per un bollente tour estivo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#listItem","position":3,"name":"GOGOL BORDELLO: in Italia per un bollente tour estivo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/","name":"Redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#authorImage","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/05\/Logo-150x150.jpg","width":96,"height":96,"caption":"Redazione"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/","name":"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP","description":"GOGOL BORDELLO: in Italia per un bollente tour estivo","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2018\/03\/GOGOL-BORDELLO_2018.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#mainImage","width":550,"height":413},"primaryImageOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/#mainImage"},"datePublished":"2018-03-06T12:00:04+01:00","dateModified":"2018-03-03T18:41:54+01:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP","og:description":"GOGOL BORDELLO: in Italia per un bollente tour estivo","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/","article:published_time":"2018-03-06T11:00:04+00:00","article:modified_time":"2018-03-03T17:41:54+00:00","twitter:card":"summary","twitter:title":"GOGOL BORDELLO: in Italia per un bollente tour estivo | Piu o Meno POP","twitter:description":"GOGOL BORDELLO: in Italia per un bollente tour estivo"},"aioseo_meta_data":{"post_id":"30393","title":"GOGOL BORDELLO: in Italia per un bollente tour estivo | #site_title","description":"GOGOL BORDELLO: in Italia per un bollente tour estivo","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 18:18:09","updated":"2026-06-22 07:10:46","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/\" title=\"Notizie\">Notizie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGOGOL BORDELLO: in Italia per un bollente tour estivo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Notizie","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/"},{"label":"GOGOL BORDELLO: in Italia per un bollente tour estivo","link":"https:\/\/www.piuomenopop.it\/index.php\/2018\/03\/06\/gogol-bordello-in-italia-per-un-bollente-tour-estivo\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/30393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=30393"}],"version-history":[{"count":1,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/30393\/revisions"}],"predecessor-version":[{"id":30395,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/30393\/revisions\/30395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/30394"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=30393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=30393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=30393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}