{"id":3333,"date":"2016-07-13T15:24:50","date_gmt":"2016-07-13T13:24:50","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=3333"},"modified":"2018-01-01T18:34:18","modified_gmt":"2018-01-01T17:34:18","slug":"riccioli","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/","title":{"rendered":"Riccioli"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3334 aligncenter\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/07\/vetro-rotto.jpg\" alt=\"vetro-rotto\" width=\"450\" height=\"254\" \/><span style=\"font-size: 8pt;\">Foto <a href=\"http:\/\/tamalesyatole.deviantart.com\/art\/Bright-Broken-Tempered-Sheet-of-Glass-334031376\" target=\"_blank\">Deviantart<\/a><\/span><\/p>\n<p>Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me. pace, mettiti l&#8217;anima in pace.<!--more--><\/p>\n<p>Il primo pensiero si poggia leggero sulla tua cucina, io seduta al tavolo immersa da fotocopie da studiare, tu in piedi ai fornelli prepari il caff\u00e8. bermudino rosso, quello osceno che ti andava largo e calzino nero lungo in bella vista, felpa vecchia consumata sulle maniche e ricciolini scomposti. &#8220;Ci posso affondare la mano?? Ti prego, sono il mio antistress!&#8221; &#8230;che domande? Certo che potevo farlo! Quello era il centro del mio mondo, tutto si congelava, scioglieva, viveva e moriva l\u00ec dove eri tu. gli abbandoni. Ma quanto \u00e8 stato facile? Ti\u00a0immagino ora come un treno, veloce, compatto, determinato lungo la meta, che corre sui binari senza indugiare a quella fermata dove i pezzi del vaso, ormai polvere, sono stati spazzati via. Per\u00f2 eccomi, io sono proprio l\u00ec, su una panchina di legno a guardare quel treno che, fedele, ha avuto un posto a sedere per me. mi alzer\u00f2 mai? Bussano alla porta, nel frattempo mi alzo dal letto.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Foto Deviantart Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/\" title=\"Riccioli\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[135],"tags":[621,479,57,161,620],"class_list":["post-3333","post","type-post","status-publish","format-standard","hentry","category-in-medias-res","tag-articoli","tag-in-media-res","tag-piuomenopop","tag-racconti","tag-racconto"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fiorella Todisco\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Riccioli | Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-07-13T13:24:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-01-01T17:34:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Riccioli | Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#blogposting\",\"name\":\"Riccioli | Piu o Meno POP\",\"headline\":\"Riccioli\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/fiorellatodisco\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/vetro-rotto.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#articleImage\"},\"datePublished\":\"2016-07-13T15:24:50+02:00\",\"dateModified\":\"2018-01-01T18:34:18+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#webpage\"},\"articleSection\":\"In Medias Res, articoli, in media res, piuomenopop, racconti, racconto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/#listItem\",\"name\":\"Pop Stories\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/#listItem\",\"position\":2,\"name\":\"Pop Stories\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/in-medias-res\\\/#listItem\",\"name\":\"In Medias Res\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/in-medias-res\\\/#listItem\",\"position\":3,\"name\":\"In Medias Res\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/in-medias-res\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#listItem\",\"name\":\"Riccioli\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/#listItem\",\"name\":\"Pop Stories\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#listItem\",\"position\":4,\"name\":\"Riccioli\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/pop-stories\\\/in-medias-res\\\/#listItem\",\"name\":\"In Medias Res\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/fiorellatodisco\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/fiorellatodisco\\\/\",\"name\":\"Fiorella Todisco\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f014933dd3cd8746ff9edabc782a4237d3d6d77b8e37a1a9821ebfff1313c5?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Fiorella Todisco\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/\",\"name\":\"Riccioli | Piu o Meno POP\",\"description\":\"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2016\\\/07\\\/13\\\/riccioli\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/fiorellatodisco\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/fiorellatodisco\\\/#author\"},\"datePublished\":\"2016-07-13T15:24:50+02:00\",\"dateModified\":\"2018-01-01T18:34:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Riccioli | Piu o Meno POP","description":"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#blogposting","name":"Riccioli | Piu o Meno POP","headline":"Riccioli","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/fiorellatodisco\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2016\/07\/vetro-rotto.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#articleImage"},"datePublished":"2016-07-13T15:24:50+02:00","dateModified":"2018-01-01T18:34:18+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#webpage"},"articleSection":"In Medias Res, articoli, in media res, piuomenopop, racconti, racconto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/#listItem","name":"Pop Stories"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/#listItem","position":2,"name":"Pop Stories","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/in-medias-res\/#listItem","name":"In Medias Res"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/in-medias-res\/#listItem","position":3,"name":"In Medias Res","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/in-medias-res\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#listItem","name":"Riccioli"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/#listItem","name":"Pop Stories"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#listItem","position":4,"name":"Riccioli","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/in-medias-res\/#listItem","name":"In Medias Res"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/fiorellatodisco\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/fiorellatodisco\/","name":"Fiorella Todisco","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c1f014933dd3cd8746ff9edabc782a4237d3d6d77b8e37a1a9821ebfff1313c5?s=96&d=mm&r=g","width":96,"height":96,"caption":"Fiorella Todisco"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/","name":"Riccioli | Piu o Meno POP","description":"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/fiorellatodisco\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/fiorellatodisco\/#author"},"datePublished":"2016-07-13T15:24:50+02:00","dateModified":"2018-01-01T18:34:18+01:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"Riccioli | Piu o Meno POP","og:description":"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/","article:published_time":"2016-07-13T13:24:50+00:00","article:modified_time":"2018-01-01T17:34:18+00:00","twitter:card":"summary","twitter:title":"Riccioli | Piu o Meno POP","twitter:description":"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me"},"aioseo_meta_data":{"post_id":"3333","title":"Riccioli | #site_title","description":"Mi sono sdraiata sul mio letto con le luci spente, ho avviato una playlist a caso e ho salutato la fredda contingenza delle cose che erano intorno a me","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 13:57:17","updated":"2026-06-22 00:10:45","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/\" title=\"Pop Stories\">Pop Stories<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/in-medias-res\/\" title=\"In Medias Res\">In Medias Res<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRiccioli\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Pop Stories","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/"},{"label":"In Medias Res","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/pop-stories\/in-medias-res\/"},{"label":"Riccioli","link":"https:\/\/www.piuomenopop.it\/index.php\/2016\/07\/13\/riccioli\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/3333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=3333"}],"version-history":[{"count":6,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/3333\/revisions"}],"predecessor-version":[{"id":3341,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/3333\/revisions\/3341"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=3333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=3333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=3333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}