{"id":49115,"date":"2019-05-26T23:09:36","date_gmt":"2019-05-26T21:09:36","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=49115"},"modified":"2019-05-26T23:09:36","modified_gmt":"2019-05-26T21:09:36","slug":"lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/","title":{"rendered":"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: center;\"><span style=\"font-size: 14pt;\"><strong>Lo Stato Sociale per Mediterranea Saving Humans<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\"><strong>Lo Stato Sociale<\/strong>\u00a0torna sui temi dell\u2019immigrazione con la realizzazione di\u00a0<strong>un breve documentario<\/strong>\u00a0in cui racconta\u00a0<strong>l\u2019addestramento delle squadre di soccorso<\/strong>di\u00a0<strong>Mediterranea Saving Humans.<\/strong><br \/>\nIl documentario diretto da\u00a0<strong>Davide Spina<\/strong>\u00a0\u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto\u00a0<strong>(Carota)<\/strong>. La band si era gi\u00e0 occupata dei temi del tema degli sbarchi nella canzone\u00a0<strong><em>Socialismo Tropicale<\/em><\/strong>, pubblicata nel 2017 per\u00a0<strong>Garrincha Dischi\/<\/strong>\u00a0<strong>Island Records<\/strong>nasce in ricordo delle vittime della tragedia di Portopalo, avvenuta nella notte tra il 24 e il 25 dicembre 1996, in cui sono morte in mare 283 persone nel tentativo di arrivare in Italia.<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/lHm7cWN8dCw\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"font-weight: 400;\">\u201c<em>La Mare Jonio, la nave di Mediterranea, \u00e8 al centro di un\u2019inchiesta giudiziaria per aver salvato 30 persone in mare e averle portate in Italia invece che affidarle alla Libia e ai suoi centri di detenzione, ormai veri e propri lager.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Mediterranea \u00e8 un progetto di futuro, \u00e8 un progetto che mette prima di tutto l\u2019umanit\u00e0. Evitare che le persone muoiano in mare \u00e8 il minimo livello di umanit\u00e0 possibile. Poi ci vorrebbe una legislazione capace di valorizzare la ricchezza della diversit\u00e0, una legge non escludente e soprattutto non schiavizzante. Oggi le varie leggi Bossi-Fini, Minniti-Orlando e Salvini rendono uomini e donne clandestini senza diritti favorendo il proliferare di nuovi fenomeni di schiavismo piuttosto che incentivando un reale processo di integrazione.\u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Su Mediterranea ci siamo anche noi. Carota \u00e8 pronto per partire, ha partecipato ai corsi di formazione. Noi altri siamo pronti ugualmente.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Ma cosa fa Mediterranea? Come si prepara a salvare le persone? Com\u2019\u00e8 organizzata?<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Vi raccontiamo tutto questo con un video.\u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Lo Stato Sociale \u00e8 dalla parte dell\u2019umanit\u00e0, sempre<\/em>!\u201d<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Per pi\u00f9 informazioni sul progetto e per contribuire affinch\u00e9 Mediterranea continui la sua missione di denuncia e salvataggio \u00e8 possibile consultare il sito di\u00a0<a href=\"https:\/\/mediterranearescue.org\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/mediterranearescue.org\/&amp;source=gmail&amp;ust=1558990801103000&amp;usg=AFQjCNEDc47p6lCyXptN9o-dkD66U2nJGw\">https:\/\/mediterranearescue.org\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Lo Stato Sociale per Mediterranea Saving Humans &nbsp; Lo Stato Sociale\u00a0torna sui temi dell\u2019immigrazione con la realizzazione di\u00a0un breve documentario\u00a0in cui racconta\u00a0l\u2019addestramento delle squadre di <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/\" title=\"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":49116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[3427,9850],"class_list":["post-49115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-lo-stato-sociale","tag-mediterranea-saving-humans"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"redazione\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-26T21:09:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-26T21:09:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#blogposting\",\"name\":\"LO STATO SOCIALE \\u2013 IL DOCUMENTARIO SULL\\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP\",\"headline\":\"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mediterranea.jpg\",\"width\":820,\"height\":360},\"datePublished\":\"2019-05-26T23:09:36+02:00\",\"dateModified\":\"2019-05-26T23:09:36+02:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#webpage\"},\"articleSection\":\"Notizie, Lo Stato Sociale, Mediterranea Saving Humans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#listItem\",\"name\":\"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#listItem\",\"position\":3,\"name\":\"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2feb58192bb409d31bb30564805c9ab4588e2df3a00e7e57648d81c2cc138a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"redazione\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/\",\"name\":\"LO STATO SOCIALE \\u2013 IL DOCUMENTARIO SULL\\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP\",\"description\":\"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \\u00e8 stato realizzato durante l\\u2019esercitazione palermitana dell\\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\\u00e0 occupata dei temi del tema\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mediterranea.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#mainImage\",\"width\":820,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2019\\\/05\\\/26\\\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\\\/#mainImage\"},\"datePublished\":\"2019-05-26T23:09:36+02:00\",\"dateModified\":\"2019-05-26T23:09:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP","description":"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#blogposting","name":"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP","headline":"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2019\/05\/mediterranea.jpg","width":820,"height":360},"datePublished":"2019-05-26T23:09:36+02:00","dateModified":"2019-05-26T23:09:36+02:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#webpage"},"articleSection":"Notizie, Lo Stato Sociale, Mediterranea Saving Humans"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","position":2,"name":"Notizie","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#listItem","name":"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#listItem","position":3,"name":"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/","name":"redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5a2feb58192bb409d31bb30564805c9ab4588e2df3a00e7e57648d81c2cc138a?s=96&d=mm&r=g","width":96,"height":96,"caption":"redazione"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/","name":"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP","description":"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2019\/05\/mediterranea.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#mainImage","width":820,"height":360},"primaryImageOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/#mainImage"},"datePublished":"2019-05-26T23:09:36+02:00","dateModified":"2019-05-26T23:09:36+02:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP","og:description":"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/","article:published_time":"2019-05-26T21:09:36+00:00","article:modified_time":"2019-05-26T21:09:36+00:00","twitter:card":"summary","twitter:title":"LO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS - Piu o Meno POP","twitter:description":"Lo Stato Sociale per Mediterranea Saving Humans Lo Stato Sociale torna sui temi dell\u2019immigrazione con la realizzazione di un breve documentario in cui racconta l\u2019addestramento delle squadre di soccorsodi Mediterranea Saving Humans. Il documentario diretto da Davide Spina \u00e8 stato realizzato durante l\u2019esercitazione palermitana dell\u2019organizzazione a cui ha partecipato Enrico Roberto (Carota). La band si era gi\u00e0 occupata dei temi del tema"},"aioseo_meta_data":{"post_id":"49115","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 21:25:11","updated":"2026-06-22 12:30:46","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/\" title=\"Notizie\">Notizie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLO STATO SOCIALE \u2013 IL DOCUMENTARIO SULL\u2019ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Notizie","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/"},{"label":"LO STATO SOCIALE &#8211; IL DOCUMENTARIO SULL&#8217;ADDESTRAMENTO DELLE SQUADRE DI SOCCORSO DI MEDITERRANEA SAVING HUMANS","link":"https:\/\/www.piuomenopop.it\/index.php\/2019\/05\/26\/lo-stato-sociale-il-documentario-sulladdestramento-delle-squadre-di-soccorso-di-mediterranea-saving-humans\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/49115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=49115"}],"version-history":[{"count":1,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/49115\/revisions"}],"predecessor-version":[{"id":49117,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/49115\/revisions\/49117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/49116"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=49115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=49115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=49115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}