{"id":63874,"date":"2020-06-29T20:52:39","date_gmt":"2020-06-29T18:52:39","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=63874"},"modified":"2020-06-29T20:52:39","modified_gmt":"2020-06-29T18:52:39","slug":"the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/","title":{"rendered":"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce"},"content":{"rendered":"<p style=\"font-weight: 400;\">La\u00a0<strong>formazione rapcore romana<\/strong>\u00a0\u00e8 alla\u00a0<strong>ricerca di una voce solista<\/strong>. La band che finora si \u00e8 avvalsa della collaborazione occasionale di\u00a0<strong>MC provenienti da tutta la scena Hip-Hop nazionale<\/strong>, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente.<\/p>\n<p style=\"font-weight: 400;\">La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente\u00a0<strong>tra le rime del rap e le parti pi\u00f9 pesanti e graffianti tipiche del metal\/crossover<\/strong>. Per partecipare alle selezioni basta scaricare la base inedita realizzata dalla band a questo indirizzo:\u00a0<a href=\"http:\/\/www.theoldskull.it\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.theoldskull.it&amp;source=gmail&amp;ust=1593542973257000&amp;usg=AFQjCNH931fu0rc8FndIfmgWA4-Nn7nhJw\">www.theoldskull.it<\/a>, registrare la propria linea vocale (audio o video) e inviarla alla mail:\u00a0<a href=\"mailto:theoldskull83@gmail.com\">theoldskull83@gmail.com<\/a>. Il termine per inviare il materiale \u00e8 venerd\u00ec 17 Luglio mentre il risultato verr\u00e0 annunciato una settimana dopo.<\/p>\n<p style=\"font-weight: 400;\">Il vincitore parteciper\u00e0 alla realizzazione di un inedito, che verr\u00e0 inserito all\u2019interno del prossimo album dei The Old Skull, e il cantante sar\u00e0 quindi coinvolto in prima persona tra registrazioni in studio, prove e attivit\u00e0 live, magari diventando un giorno il frontman della band. La band composta da Luca Martino (batteria), Francesco Persia (chitarra), Emanuele Calvelli (basso), Alex Merola (chitarra) e DJ Snifta, reduce dalla pubblicazione dell\u2019<strong>album\u00a0<\/strong>\u201c<strong>Fantasmi, Ruggine e Rumore<\/strong>\u201d, ha recentemente\u00a0<strong>omaggiato la storica formazione Beastie Boys<\/strong>. Con la pubblicazione della cover \u201cSay It\u201d dall\u2019album \u201cHot Sauce Committee Part Two\u201d, hanno dichiarato: \u201c<em>I Beastie Boys sono il simbolo della contaminazione nella musica, questo \u00e8 un piccolissimo omaggio ad una band immensa che a distanza di anni non smette mai di emozionarci ed ispirarci<\/em>\u201d.<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/1ItKkULvp-M\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La\u00a0formazione rapcore romana\u00a0\u00e8 alla\u00a0ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di\u00a0MC provenienti da tutta la scena Hip-Hop <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/\" title=\"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":63875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[11369],"class_list":["post-63874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-the-old-skull"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"redazione\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP\" \/>\n\t\t<meta property=\"og:description\" content=\"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-29T18:52:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-29T18:52:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#blogposting\",\"name\":\"The Old Skull cercano un cantante, al via il contest \\u201cOne Minute Alone\\u201d per scoprire una nuova voce - Piu o Meno POP\",\"headline\":\"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce\",\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/The-Old-Skull.jpg\",\"width\":700,\"height\":467},\"datePublished\":\"2020-06-29T20:52:39+02:00\",\"dateModified\":\"2020-06-29T20:52:39+02:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#webpage\"},\"articleSection\":\"Notizie, The Old Skull\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#listItem\",\"name\":\"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#listItem\",\"position\":3,\"name\":\"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"Notizie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2feb58192bb409d31bb30564805c9ab4588e2df3a00e7e57648d81c2cc138a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"redazione\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#webpage\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/\",\"name\":\"The Old Skull cercano un cantante, al via il contest \\u201cOne Minute Alone\\u201d per scoprire una nuova voce - Piu o Meno POP\",\"description\":\"La formazione rapcore romana \\u00e8 alla ricerca di una voce solista. La band che finora si \\u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/author\\\/sonia\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/The-Old-Skull.jpg\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#mainImage\",\"width\":700,\"height\":467},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/index.php\\\/2020\\\/06\\\/29\\\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\\\/#mainImage\"},\"datePublished\":\"2020-06-29T20:52:39+02:00\",\"dateModified\":\"2020-06-29T20:52:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#website\",\"url\":\"https:\\\/\\\/www.piuomenopop.it\\\/\",\"name\":\"Piu o Meno POP\",\"description\":\"uno spazio di condivisione, che si occupa di passioni\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.piuomenopop.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP","description":"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap","canonical_url":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#blogposting","name":"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP","headline":"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce","author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author"},"publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2020\/06\/The-Old-Skull.jpg","width":700,"height":467},"datePublished":"2020-06-29T20:52:39+02:00","dateModified":"2020-06-29T20:52:39+02:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#webpage"},"isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#webpage"},"articleSection":"Notizie, The Old Skull"},{"@type":"BreadcrumbList","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","position":1,"name":"Home","item":"https:\/\/www.piuomenopop.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","position":2,"name":"Notizie","item":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#listItem","name":"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#listItem","position":3,"name":"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce","previousItem":{"@type":"ListItem","@id":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/#listItem","name":"Notizie"}}]},{"@type":"Organization","@id":"https:\/\/www.piuomenopop.it\/#organization","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","url":"https:\/\/www.piuomenopop.it\/"},{"@type":"Person","@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author","url":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/","name":"redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5a2feb58192bb409d31bb30564805c9ab4588e2df3a00e7e57648d81c2cc138a?s=96&d=mm&r=g","width":96,"height":96,"caption":"redazione"}},{"@type":"WebPage","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#webpage","url":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/","name":"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP","description":"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.piuomenopop.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#breadcrumblist"},"author":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author"},"creator":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/author\/sonia\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2020\/06\/The-Old-Skull.jpg","@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#mainImage","width":700,"height":467},"primaryImageOfPage":{"@id":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/#mainImage"},"datePublished":"2020-06-29T20:52:39+02:00","dateModified":"2020-06-29T20:52:39+02:00"},{"@type":"WebSite","@id":"https:\/\/www.piuomenopop.it\/#website","url":"https:\/\/www.piuomenopop.it\/","name":"Piu o Meno POP","description":"uno spazio di condivisione, che si occupa di passioni","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.piuomenopop.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Piu o Meno POP - uno spazio di condivisione, che si occupa di passioni","og:type":"article","og:title":"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP","og:description":"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap","og:url":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/","article:published_time":"2020-06-29T18:52:39+00:00","article:modified_time":"2020-06-29T18:52:39+00:00","twitter:card":"summary","twitter:title":"The Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce - Piu o Meno POP","twitter:description":"La formazione rapcore romana \u00e8 alla ricerca di una voce solista. La band che finora si \u00e8 avvalsa della collaborazione occasionale di MC provenienti da tutta la scena Hip-Hop nazionale, ha aperto i provini per cercare un nuovo componente da coinvolgere abitualmente. La figura ricercata deve saper cantare e comporre in italiano e muoversi agilmente tra le rime del rap"},"aioseo_meta_data":{"post_id":"63874","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-22 23:51:10","updated":"2026-06-22 16:39:06","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/\" title=\"Notizie\">Notizie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tThe Old Skull cercano un cantante, al via il contest \u201cOne Minute Alone\u201d per scoprire una nuova voce\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.piuomenopop.it"},{"label":"Notizie","link":"https:\/\/www.piuomenopop.it\/index.php\/category\/news\/"},{"label":"The Old Skull cercano un cantante, al via il contest &#8220;One Minute Alone&#8221; per scoprire una nuova voce","link":"https:\/\/www.piuomenopop.it\/index.php\/2020\/06\/29\/the-old-skull-cercano-un-cantante-al-via-il-contest-one-minute-alone-per-scoprire-una-nuova-voce\/"}],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/63874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=63874"}],"version-history":[{"count":1,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/63874\/revisions"}],"predecessor-version":[{"id":63876,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/63874\/revisions\/63876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/63875"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=63874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=63874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=63874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}