{"id":66333,"date":"2021-03-31T19:39:37","date_gmt":"2021-03-31T17:39:37","guid":{"rendered":"http:\/\/www.piuomenopop.it\/?p=66333"},"modified":"2021-03-31T19:41:21","modified_gmt":"2021-03-31T17:41:21","slug":"massimo-pericolo-il-9-aprile-il-live-show-per-amazon-music-per-la-prima-volta-in-italia","status":"publish","type":"post","link":"https:\/\/www.piuomenopop.it\/index.php\/2021\/03\/31\/massimo-pericolo-il-9-aprile-il-live-show-per-amazon-music-per-la-prima-volta-in-italia\/","title":{"rendered":"MASSIMO PERICOLO: il 9 aprile il live show per AMAZON MUSIC per la prima volta in Italia. Partono oggi le prevendite per il tour invernale 2021"},"content":{"rendered":"<p>Venerd\u00ec 9 aprile Massimo Pericolo si esibir\u00e0 per il primo live show in Italia di Amazon Music in diretta su Twitch dove performer\u00e0 il suo nuovo\u00a0album &#8220;Solo Tutto&#8221; uscito\u00a0venerd\u00ec 26 marzo e le sue canzoni pi\u00f9 di successo.<\/p>\n<p>Non sar\u00e0 un semplice concerto in streaming\u00a0ma un vero show imperdibile con la regia di Pepsy Romanoff (gi\u00e0 al lavoro per i music live di\u00a0Vasco Rossi, Pharrell Williams, Tinie Tempah ed altri) e di Andrea Folino (uno dei videomaker pi\u00f9 quotati nel panorama musicale italiano) per una\u00a0produzione targata Except.<\/p>\n<p>L&#8217;idea del live show legato al lancio dell&#8217;album &#8220;Solo Tutto&#8221; di Massimo Pericolo arriva in un periodo in cui a conseguenza delle restrizioni legate alla pandemia di COVID-19, in Italia non si tengono concerti da pi\u00f9 di un anno e cos\u00ec ne parla Oliver Dawson CEO dell&#8217;etichetta\u00a0Pluggers:<\/p>\n<p><em>&#8220;Parlando con Vane l\u2019idea di fare un live ci ha subito entusiasmato. Tanto del suo successo \u00e8 stato merito del suo carisma sul palco ed era un peccato non sfruttarlo. Insieme abbiamo ideato uno spettacolo che fosse realizzato apposta per il livestream, un vero e proprio show e non solo un concerto in diretta&#8221;.<\/em><\/p>\n<p>Il live show di Massimo Pericolo sar\u00e0 presentato da Carlo Pastore e verr\u00e0 trasmesso dal Teatro LaCucina, una location\u00a0particolare che nasce l\u00ec dove una volta c&#8217;era la mensa dell&#8217;ex ospedale psichiatrico Paolo Pini, un luogo suggestivo che ospiter\u00e0 il primo concerto in streaming per Amazon Music in Italia.<\/p>\n<p>La piattaforma scelta sar\u00e0 Twitch dove di recente l&#8217;artista della provincia di Varese ha aperto un canale nel quale ha comunicato, nei giorni precedenti al lancio del disco, i singoli e i featuring di &#8220;Solo Tutto&#8221;.<\/p>\n<p>Il live show di Massimo Pericolo per Amazon Music si terr\u00e0 venerd\u00ec 9 aprile\u00a0su Twitch e la visione sar\u00e0 gratuita.<\/p>\n<p><a href=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2021\/03\/pericolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-66334\" src=\"http:\/\/www.piuomenopop.it\/wp-content\/uploads\/2021\/03\/pericolo.jpg\" alt=\"\" width=\"480\" height=\"600\" srcset=\"https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2021\/03\/pericolo.jpg 1181w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2021\/03\/pericolo-240x300.jpg 240w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2021\/03\/pericolo-768x960.jpg 768w, https:\/\/www.piuomenopop.it\/wp-content\/uploads\/2021\/03\/pericolo-819x1024.jpg 819w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n<p><strong>Solo Tutto<\/strong><\/p>\n<p>&#8220;Solo Tutto&#8221;, il nuovo atteso album di Massimo Pericolo, uno degli artisti italiani pi\u00f9 forti del momento, \u00e8 finalmente uscito\u00a0ed \u00e8 disponibile su tutte le piattaforme digitali e nel formato fisico per Pluggers e LuckyBeardRec in collaborazione con Epic\/Sony Music Italy.<\/p>\n<p>Anticipato dal singolo &#8220;Bugie&#8221;, il secondo disco di Massimo Pericolo \u00e8 la consacrazione di un percorso che iniziato due anni fa con la canzone &#8220;7 Miliardi&#8221;, passando per l&#8217;album Disco di Platino\u00a0&#8220;Scialla Semper&#8221; e una serie di collaborazioni di successo, lo ha portato nell&#8217;Olimpo della scena musicale italiana.<\/p>\n<p>L&#8217;album &#8220;Solo Tutto&#8221; \u00e8\u00a0un viaggio nel passato e presente dell&#8217;artista. Ogni canzone fotografa un momento diverso della sua vita e racconta, con una capacit\u00e0 fuori dal comune, la realt\u00e0 cruda di un ragazzo di provincia. Ironia, rabbia, dolcezza sono le armi che usa per parlare di relazioni, successo, soldi e riscatto sociale, e grazie ai quali possiamo vedere il mondo attraverso gli occhi di uno degli artisti pi\u00f9 unici della sua generazione.<\/p>\n<p>Il nuovo disco di Massimo Pericolo presenta quindici canzoni dove ad accompagnarlo c&#8217;\u00e8 Salmo in &#8220;Cazzo Culo&#8221;, Madame in &#8220;Airforce&#8221;, J Lord in &#8220;Troia&#8221; e Venerus nella traccia d&#8217;apertura &#8220;Casa Nuova&#8221;. L&#8217;intero album \u00e8 prodotto da Crookers che come nel precedente &#8220;Scialla Semper&#8221; fa sentire il suo peso artistico e la sua esperienza internazionale con un sound nuovo e di rilievo\u00a0per il\u00a0panorama italiano. Insieme a lui\u00a0Nic Sarno e Goedi nelle coproduzioni di alcune tracce a comporre il puzzle di uno degli album pi\u00f9 attesti dell&#8217;anno.<\/p>\n<p>&#8220;Solo Tutto&#8221; \u00e8 disponibile in streaming su tutte le piattaforme digitali e nel formato fisico in cinque differenti versioni:<\/p>\n<p>&#8211; Deluxe Box CD + Cerchietto Orecchie Gatto + poster (<a href=\"https:\/\/facebook.us16.list-manage.com\/track\/click?u=64b140f2dc679d23e8af8eb48&amp;id=2c648bff16&amp;e=050554102e\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/facebook.us16.list-manage.com\/track\/click?u%3D64b140f2dc679d23e8af8eb48%26id%3D2c648bff16%26e%3D050554102e&amp;source=gmail&amp;ust=1617268307531000&amp;usg=AFQjCNFlp1T86vO8G2GbxteeTKqdViP5DA\">link<\/a>)<br \/>\n&#8211; CD con poster autografato (<a href=\"https:\/\/facebook.us16.list-manage.com\/track\/click?u=64b140f2dc679d23e8af8eb48&amp;id=c21a275c8b&amp;e=050554102e\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/facebook.us16.list-manage.com\/track\/click?u%3D64b140f2dc679d23e8af8eb48%26id%3Dc21a275c8b%26e%3D050554102e&amp;source=gmail&amp;ust=1617268307531000&amp;usg=AFQjCNHJ3Ml9GLXStym-dyU48hsFJHXY6g\">link<\/a>)<br \/>\n&#8211; 2LP Vinile nero 180 gr (<a href=\"https:\/\/facebook.us16.list-manage.com\/track\/click?u=64b140f2dc679d23e8af8eb48&amp;id=1eb7026a01&amp;e=050554102e\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/facebook.us16.list-manage.com\/track\/click?u%3D64b140f2dc679d23e8af8eb48%26id%3D1eb7026a01%26e%3D050554102e&amp;source=gmail&amp;ust=1617268307531000&amp;usg=AFQjCNECmWpA2igvP1L7fgdr2mQb6oY3Lw\">link<\/a>)<br \/>\n&#8211;\u00a02LP Vinile bianco trasparente con poster autografato\u00a0(<a href=\"https:\/\/facebook.us16.list-manage.com\/track\/click?u=64b140f2dc679d23e8af8eb48&amp;id=a57402a112&amp;e=050554102e\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/facebook.us16.list-manage.com\/track\/click?u%3D64b140f2dc679d23e8af8eb48%26id%3Da57402a112%26e%3D050554102e&amp;source=gmail&amp;ust=1617268307531000&amp;usg=AFQjCNFMIhIo6WgWPPoP3Q034Le9vC0biA\">link<\/a>)<br \/>\n&#8211; 2LP Vinile rosso\u00a0trasparente con poster autografato\u00a0(<a href=\"https:\/\/facebook.us16.list-manage.com\/track\/click?u=64b140f2dc679d23e8af8eb48&amp;id=f7b7d7c460&amp;e=050554102e\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/facebook.us16.list-manage.com\/track\/click?u%3D64b140f2dc679d23e8af8eb48%26id%3Df7b7d7c460%26e%3D050554102e&amp;source=gmail&amp;ust=1617268307531000&amp;usg=AFQjCNHlPOKTLskk41Lm6m6uTzdVYTck8A\">link<\/a>)<\/p>\n<p>Solo Tutto &#8211; Tracklist:<\/p>\n<p>1) Casa Nuova feat. Venerus (prod. Crookers &amp; Nic Sarno)<br \/>\n2) Debiti (prod. Crookers)<br \/>\n3) Cazzo Culo feat. Salmo (prod. Crookers &amp; Nic Sarno)<br \/>\n4) Sai Solo Scopare! (prod. Crookers)<br \/>\n5) Airforce feat. Madame (prod. Crookers)<br \/>\n6) G (prod. Crookers &amp; Goedi)<br \/>\n7) Bugie (prod. Crookers)<br \/>\n8) 100k (prod. Crookers &amp; Goedi)<br \/>\n9) Troia feat. J Lord (prod. Crookers)<br \/>\n10) Bang Bang (prod. Crookers)<br \/>\n11) Fumo (prod. Crookers)<br \/>\n12) Beretta (prod. Crookers)<br \/>\n13) Solo Sex (prod. Crookers &amp; Nic Sarno)<br \/>\n14) Brebbia 2012 (prod. Crookers &amp; Nic Sarno)<br \/>\n15) Stupido (prod. Crookers)<\/p>\n<p>&nbsp;<\/p>\n<p>Partono oggi le prevendite per il tour invernale 2021 di Massimo\u00a0<span class=\"il\">Pericolo<\/span> che lo porter\u00e0 a presentare il nuovo album &#8220;Solo Tutto&#8221; e i suoi classici nelle maggiori citt\u00e0 d&#8217;Italia.\u00a0 <a href=\"https:\/\/linktr.ee\/MassimoPericolo\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/linktr.ee\/MassimoPericolo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Venerd\u00ec 9 aprile Massimo Pericolo si esibir\u00e0 per il primo live show in Italia di Amazon Music in diretta su Twitch dove performer\u00e0 il suo <a class=\"mh-excerpt-more\" href=\"https:\/\/www.piuomenopop.it\/index.php\/2021\/03\/31\/massimo-pericolo-il-9-aprile-il-live-show-per-amazon-music-per-la-prima-volta-in-italia\/\" title=\"MASSIMO PERICOLO: il 9 aprile il live show per AMAZON MUSIC per la prima volta in Italia. Partono oggi le prevendite per il tour invernale 2021\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":66136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[9503,12357],"class_list":["post-66333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-massimo-pericolo","tag-solo-tutto"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/66333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/comments?post=66333"}],"version-history":[{"count":3,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/66333\/revisions"}],"predecessor-version":[{"id":66336,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/posts\/66333\/revisions\/66336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media\/66136"}],"wp:attachment":[{"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/media?parent=66333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/categories?post=66333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piuomenopop.it\/index.php\/wp-json\/wp\/v2\/tags?post=66333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}